{"id":14994,"date":"2024-10-10T03:32:10","date_gmt":"2024-10-09T19:32:10","guid":{"rendered":"https:\/\/pics.xoxdoll.com\/?post_type=product&#038;p=14994"},"modified":"2025-04-15T19:57:04","modified_gmt":"2025-04-15T11:57:04","slug":"sex-doll-with-big-ass","status":"publish","type":"product","link":"https:\/\/bomidoll.com\/it\/shop\/sex-doll-with-big-ass\/","title":{"rendered":"Bambola del sesso con culo grande"},"content":{"rendered":"<h5>Informazioni sulla bambola<\/h5>\n<h6>Perch\u00e9 acquistare una bambola del sesso con un grosso culo?<\/h6>\n<p>Questa bambola del sesso con un grande culo \u00e8 stata realizzata per combinare sia la stimolazione visiva che il feedback tattile con la funzionalit\u00e0. Ci\u00f2 \u00e8 stato fatto realizzando TPE di grado medico su una solida struttura in metallo. Ci\u00f2 fornisce le immagini migliori e pi\u00f9 realistiche mantenendo una sensazione morbida simile alla carne. La bambola del sesso con un grande culo unisce tutto per una bambola dell&#039;amore realistica e coinvolgente.<\/p>\n<p>Questa bambola del sesso con un grande culo \u00e8 stata progettata per essere il pi\u00f9 realistica e naturale possibile. Quindi, ci siamo assicurati di prestare molta attenzione ai dettagli, rispecchiando ogni centimetro di questa bambola del sesso con un grande culo alla cosa reale. Quindi, usare questa bambola del sesso con un grande culo \u00e8 proprio come avere intimit\u00e0 con la tua cotta formosa preferita.<\/p>\n<h6>Perch\u00e9 acquistare da noi una bambola del sesso con un grosso culo?<\/h6>\n<p>Questa bambola del sesso con un grosso culo dovrebbe essere spedita dalla nostra fabbrica a casa tua. Questo ti assicura di non spendere soldi extra per intermediari e i loro ricarichi. Inoltre, i nostri canali di spedizione sicuri sono molto veloci e proteggono la tua privacy come nessun altro.<\/p>\n<h5>Immagini di bambole del sesso<\/h5>\n<div id=\"envira-gallery-wrap-8446\" class=\"envira-gallery-wrap envira-lazy-loading-enabled envira-layout-automatic\" itemscope itemtype=\"https:\/\/schema.org\/ImageGallery\"><div class=\"envira-loader\"><div><\/div><div><\/div><div><\/div><div><\/div><\/div><div id=\"envira-gallery-8446\" class=\"envira-gallery-public envira-gallery-0-columns envira-clear envira-gallery-justified-public\" data-envira-id=\"8446\" data-gallery-config='{\"type\":\"default\",\"layout\":\"automatic\",\"columns\":\"0\",\"gallery_theme\":\"base\",\"justified_margins\":1,\"justified_last_row\":\"nojustify\",\"lazy_loading\":1,\"lazy_loading_delay\":500,\"gutter\":10,\"gutter_mobile\":0,\"margin\":10,\"image_size\":\"default\",\"square_size\":300,\"crop_width\":640,\"crop_height\":480,\"crop\":0,\"crop_position\":\"c\",\"show_more_text\":\"Click for more\",\"additional_copy_0\":0,\"additional_copy_title\":0,\"additional_copy_caption\":0,\"additional_copy_title_caption\":0,\"additional_copy_0_mobile\":0,\"additional_copy_title_mobile\":0,\"additional_copy_caption_mobile\":0,\"additional_copy_title_caption_mobile\":0,\"gallery_column_title_caption\":\"0\",\"gallery_column_title_caption_mobile\":\"0\",\"additional_copy_automatic_0\":0,\"additional_copy_automatic_title\":0,\"additional_copy_automatic_caption\":0,\"additional_copy_automatic_title_caption\":0,\"additional_copy_automatic_0_mobile\":0,\"additional_copy_automatic_title_mobile\":0,\"additional_copy_automatic_caption_mobile\":0,\"additional_copy_automatic_title_caption_mobile\":0,\"gallery_automatic_title_caption\":\"0\",\"gallery_automatic_title_caption_mobile\":\"0\",\"justified_row_height\":150,\"description_position\":\"0\",\"description\":\"\",\"random\":\"0\",\"sort_order\":\"0\",\"sorting_direction\":\"ASC\",\"image_sizes_random\":[],\"isotope\":0,\"lightbox_enabled\":1,\"gallery_link_enabled\":1,\"lightbox_theme\":\"base_dark\",\"lightbox_image_size\":\"default\",\"title_display\":\"float\",\"lightbox_title_caption\":\"title\",\"arrows\":1,\"arrows_position\":\"inside\",\"toolbar\":1,\"toolbar_title\":0,\"toolbar_position\":\"top\",\"loop\":1,\"lightbox_open_close_effect\":\"fade\",\"effect\":\"fade\",\"supersize\":0,\"thumbnails_toggle\":0,\"thumbnails_hide\":0,\"image_counter\":0,\"lightbox_html_caption\":0,\"thumbnails\":1,\"thumbnails_width\":\"auto\",\"thumbnails_height\":\"auto\",\"thumbnails_position\":\"bottom\",\"thumbnails_custom_size\":0,\"mobile\":1,\"mobile_width\":320,\"mobile_height\":240,\"mobile_lightbox\":1,\"mobile_gallery_link_enabled\":0,\"mobile_arrows\":1,\"mobile_toolbar\":1,\"mobile_thumbnails\":1,\"mobile_touchwipe_close\":0,\"mobile_thumbnails_width\":75,\"mobile_thumbnails_height\":50,\"mobile_justified_row_height\":80,\"keyboard\":true,\"classes\":[\"\"],\"rtl\":0,\"slug\":\"lfu165hs104\",\"gallery_id\":\"8446\"}' data-gallery-images='[{\"status\":\"active\",\"src\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"title\":\"gainoid-sex-doll-gEh75j4\",\"link\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"alt\":\"\",\"caption\":false,\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4-75x50_c.jpg\",\"meta\":{\"aperture\":null,\"credit\":null,\"camera\":null,\"caption\":\"\",\"created_timestamp\":null,\"copyright\":null,\"focal_length\":null,\"iso\":null,\"shutter_speed\":null,\"title\":\"\",\"orientation\":null,\"keywords\":null},\"thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4-150x150.jpg\",\"medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4-225x300.jpg\",\"medium_large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"1536x1536\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"2048x2048\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"trp-custom-language-flag\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"380x380\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"480x900\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"280x150\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"590x320\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"nasa-medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"woocommerce_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4-350x467.jpg\",\"woocommerce_single\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4-595x793.jpg\",\"woocommerce_gallery_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4-100x100.jpg\",\"full\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4.jpg\",\"index\":0,\"id\":8458,\"video\":false,\"opts\":{\"caption\":\"\",\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j4-75x50_c.jpg\",\"title\":\"gainoid-sex-doll-gEh75j4\"},\"gallery_id\":\"8446\"},{\"status\":\"active\",\"src\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"title\":\"gainoid-sex-doll-gEh75j5\",\"link\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"alt\":\"\",\"caption\":false,\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5-75x50_c.jpg\",\"meta\":{\"aperture\":null,\"credit\":null,\"camera\":null,\"caption\":\"\",\"created_timestamp\":null,\"copyright\":null,\"focal_length\":null,\"iso\":null,\"shutter_speed\":null,\"title\":\"\",\"orientation\":null,\"keywords\":null},\"thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5-150x150.jpg\",\"medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5-225x300.jpg\",\"medium_large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"1536x1536\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"2048x2048\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"trp-custom-language-flag\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"380x380\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"480x900\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"280x150\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"590x320\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"nasa-medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"woocommerce_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5-350x467.jpg\",\"woocommerce_single\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5-595x793.jpg\",\"woocommerce_gallery_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5-100x100.jpg\",\"full\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5.jpg\",\"index\":1,\"id\":8461,\"video\":false,\"opts\":{\"caption\":\"\",\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j5-75x50_c.jpg\",\"title\":\"gainoid-sex-doll-gEh75j5\"},\"gallery_id\":\"8446\"},{\"status\":\"active\",\"src\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"title\":\"gainoid-sex-doll-gEh75j2\",\"link\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"alt\":\"\",\"caption\":false,\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2-75x50_c.jpg\",\"meta\":{\"aperture\":null,\"credit\":null,\"camera\":null,\"caption\":\"\",\"created_timestamp\":null,\"copyright\":null,\"focal_length\":null,\"iso\":null,\"shutter_speed\":null,\"title\":\"\",\"orientation\":null,\"keywords\":null},\"thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2-150x150.jpg\",\"medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2-225x300.jpg\",\"medium_large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"1536x1536\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"2048x2048\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"trp-custom-language-flag\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"380x380\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"480x900\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"280x150\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"590x320\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"nasa-medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"woocommerce_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2-350x467.jpg\",\"woocommerce_single\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2-595x793.jpg\",\"woocommerce_gallery_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2-100x100.jpg\",\"full\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2.jpg\",\"index\":2,\"id\":8455,\"video\":false,\"opts\":{\"caption\":\"\",\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j2-75x50_c.jpg\",\"title\":\"gainoid-sex-doll-gEh75j2\"},\"gallery_id\":\"8446\"},{\"status\":\"active\",\"src\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"title\":\"gainoid-sex-doll-gEh75j3\",\"link\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"alt\":\"\",\"caption\":false,\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3-75x50_c.jpg\",\"meta\":{\"aperture\":null,\"credit\":null,\"camera\":null,\"caption\":\"\",\"created_timestamp\":null,\"copyright\":null,\"focal_length\":null,\"iso\":null,\"shutter_speed\":null,\"title\":\"\",\"orientation\":null,\"keywords\":null},\"thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3-150x150.jpg\",\"medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3-225x300.jpg\",\"medium_large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"1536x1536\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"2048x2048\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"trp-custom-language-flag\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"380x380\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"480x900\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"280x150\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"590x320\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"nasa-medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"woocommerce_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3-350x467.jpg\",\"woocommerce_single\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3-595x793.jpg\",\"woocommerce_gallery_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3-100x100.jpg\",\"full\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3.jpg\",\"index\":3,\"id\":8456,\"video\":false,\"opts\":{\"caption\":\"\",\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j3-75x50_c.jpg\",\"title\":\"gainoid-sex-doll-gEh75j3\"},\"gallery_id\":\"8446\"},{\"status\":\"active\",\"src\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"title\":\"gainoid-sex-doll-gEh75j1\",\"link\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"alt\":\"\",\"caption\":false,\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1-75x50_c.jpg\",\"meta\":{\"aperture\":null,\"credit\":null,\"camera\":null,\"caption\":\"\",\"created_timestamp\":null,\"copyright\":null,\"focal_length\":null,\"iso\":null,\"shutter_speed\":null,\"title\":\"\",\"orientation\":null,\"keywords\":null},\"thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1-150x150.jpg\",\"medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1-225x300.jpg\",\"medium_large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"large\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"1536x1536\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"2048x2048\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"trp-custom-language-flag\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"380x380\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"480x900\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"280x150\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"590x320\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"nasa-medium\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"woocommerce_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1-350x467.jpg\",\"woocommerce_single\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1-595x793.jpg\",\"woocommerce_gallery_thumbnail\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1-100x100.jpg\",\"full\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1.jpg\",\"index\":4,\"id\":8453,\"video\":false,\"opts\":{\"caption\":\"\",\"thumb\":\"https:\\\/\\\/bomidoll.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/gainoid-sex-doll-gEh75j1-75x50_c.jpg\",\"title\":\"gainoid-sex-doll-gEh75j1\"},\"gallery_id\":\"8446\"}]' data-lightbox-theme='{&quot;arrows&quot;:true,&quot;margins&quot;:[120,0],&quot;gutter&quot;:&quot;100&quot;,&quot;thumbs_position&quot;:&quot;bottom&quot;,&quot;base_template&quot;:&quot;&lt;div id=\\&quot;envirabox-8446\\&quot; data-envirabox-id=\\&quot;8446\\&quot; class=\\&quot;envirabox-container envirabox-theme-base_dark envirabox-wrap\\&quot; role=\\&quot;dialog\\&quot;&gt;&lt;div class=\\&quot;envirabox-bg\\&quot;&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;envirabox-outer\\&quot;&gt;&lt;div class=\\&quot;envirabox-inner\\&quot;&gt;&lt;div class=\\&quot;envirabox-caption-wrap\\&quot;&gt;&lt;div class=\\&quot;envirabox-title\\&quot;&gt;&lt;\\\/div&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;envirabox-toolbar\\&quot;&gt;&lt;div class=\\&quot;envira-close-button\\&quot;&gt;&lt;a data-envirabox-close class=\\&quot;envirabox-item envirabox-close envirabox-button--close\\&quot; title=\\&quot;Close\\&quot; href=\\&quot;#\\&quot;&gt;&lt;\\\/a&gt;&lt;\\\/div&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;envirabox-navigation\\&quot;&gt;&lt;a data-envirabox-prev title=\\&quot;Prev\\&quot; class=\\&quot;envirabox-arrow envirabox-arrow--left envirabox-nav envirabox-prev\\&quot; href=\\&quot;#\\&quot;&gt;&lt;span&gt;&lt;\\\/span&gt;&lt;\\\/a&gt;&lt;a data-envirabox-next title=\\&quot;Next\\&quot; class=\\&quot;envirabox-arrow envirabox-arrow--right envirabox-nav envirabox-next\\&quot; href=\\&quot;#\\&quot;&gt;&lt;span&gt;&lt;\\\/span&gt;&lt;\\\/a&gt;&lt;\\\/div&gt;&lt;div class=\\&quot;envirabox-stage\\&quot;&gt;&lt;\\\/div&gt;&lt;\\\/div&gt;&lt;\\\/div&gt;&lt;\\\/div&gt;&quot;,&quot;load_all&quot;:false,&quot;error_template&quot;:&quot;&lt;div class=\\&quot;envirabox-error\\&quot;&gt;&lt;p&gt;{{ERROR}}&lt;p&gt;&lt;\\\/div&gt;&quot;,&quot;inner_caption&quot;:false,&quot;caption_position&quot;:false,&quot;arrow_position&quot;:false,&quot;toolbar&quot;:true,&quot;infobar&quot;:false,&quot;show_smallbtn&quot;:false,&quot;idle_time&quot;:false,&quot;click_content&quot;:false,&quot;click_slide&quot;:false,&quot;click_outside&quot;:false,&quot;animation_duration&quot;:false,&quot;transition_duration&quot;:false,&quot;small_btn_template&quot;:&quot;&lt;a data-envirabox-close class=\\&quot;envirabox-item envirabox-close envirabox-button--close\\&quot; title=\\&quot;Close\\&quot; href=\\&quot;#\\&quot;&gt;&lt;\\\/a&gt;&quot;}' data-parsed-attrs='{\"id\":\"8446\",\"cache\":true}'><div id=\"envira-gallery-item-8458\" class=\"envira-gallery-item envira-gallery-item-1 envira-lazy-load\" style=\"padding-left: 5px; padding-bottom: 10px; padding-right: 5px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-right\"><\/div><a class=\"envira-gallery-8446 envira-gallery-link\" href=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j4.jpg\" title=\"bambola-del-sesso-gainoid-gEh75j4\" data-caption=\"\" data-envira-item-id=\"8458\" data-envira-retina=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j4.jpg\" data-thumb=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j4-75x50_c.jpg\" data-title=\"gainoid-sex-doll-gEh75j4\" data-envirabox='8446' itemprop=\"contentUrl\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j4.jpg\" alt=\"\" class=\"envira-gallery-image envira-gallery-image-1    envira-lazy\" height=\"480\" id=\"envira-gallery-image-8458\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" tabindex=\"-1\" title=\"bambola-del-sesso-gainoid-gEh75j4\" width=\"640\" data-caption=\"\" data-envira-gallery-id=\"8446\" data-envira-index=\"0\" data-envira-item-id=\"8458\" data-envira-src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j4.jpg\" data-envira-srcset=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j4.jpg 400w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j4.jpg 2x\" data-title=\"gainoid-sex-doll-gEh75j4\" itemprop=\"thumbnailUrl\" data-envirabox=\"8446\" data-automatic-caption=\"\" data-envira-height=\"300\" data-envira-width=\"225\" data-envira- data-><\/a><\/div><\/div><div id=\"envira-gallery-item-8461\" class=\"envira-gallery-item envira-gallery-item-2 envira-lazy-load\" style=\"padding-left: 5px; padding-bottom: 10px; padding-right: 5px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-right\"><\/div><a class=\"envira-gallery-8446 envira-gallery-link\" href=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j5.jpg\" title=\"bambola-del-sesso-gainoid-gEh75j5\" data-caption=\"\" data-envira-item-id=\"8461\" data-envira-retina=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j5.jpg\" data-thumb=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j5-75x50_c.jpg\" data-title=\"gainoid-sex-doll-gEh75j5\" data-envirabox='8446' itemprop=\"contentUrl\"><img decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j5.jpg\" alt=\"\" class=\"envira-gallery-image envira-gallery-image-2    envira-lazy\" height=\"480\" id=\"envira-gallery-image-8461\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" tabindex=\"-1\" title=\"bambola-del-sesso-gainoid-gEh75j5\" width=\"640\" data-caption=\"\" data-envira-gallery-id=\"8446\" data-envira-index=\"1\" data-envira-item-id=\"8461\" data-envira-src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j5.jpg\" data-envira-srcset=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j5.jpg 400w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j5.jpg 2x\" data-title=\"gainoid-sex-doll-gEh75j5\" itemprop=\"thumbnailUrl\" data-envirabox=\"8446\" data-automatic-caption=\"\" data-envira-height=\"300\" data-envira-width=\"225\" data-envira- data-><\/a><\/div><\/div><div id=\"envira-gallery-item-8455\" class=\"envira-gallery-item envira-gallery-item-3 envira-lazy-load\" style=\"padding-left: 5px; padding-bottom: 10px; padding-right: 5px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-right\"><\/div><a class=\"envira-gallery-8446 envira-gallery-link\" href=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j2.jpg\" title=\"bambola-del-sesso-gainoid-gEh75j2\" data-caption=\"\" data-envira-item-id=\"8455\" data-envira-retina=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j2.jpg\" data-thumb=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j2-75x50_c.jpg\" data-title=\"gainoid-sex-doll-gEh75j2\" data-envirabox='8446' itemprop=\"contentUrl\"><img decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j2.jpg\" alt=\"\" class=\"envira-gallery-image envira-gallery-image-3    envira-lazy\" height=\"480\" id=\"envira-gallery-image-8455\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" tabindex=\"-1\" title=\"bambola-del-sesso-gainoid-gEh75j2\" width=\"640\" data-caption=\"\" data-envira-gallery-id=\"8446\" data-envira-index=\"2\" data-envira-item-id=\"8455\" data-envira-src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j2.jpg\" data-envira-srcset=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j2.jpg 400w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j2.jpg 2x\" data-title=\"gainoid-sex-doll-gEh75j2\" itemprop=\"thumbnailUrl\" data-envirabox=\"8446\" data-automatic-caption=\"\" data-envira-height=\"300\" data-envira-width=\"225\" data-envira- data-><\/a><\/div><\/div><div id=\"envira-gallery-item-8456\" class=\"envira-gallery-item envira-gallery-item-4 envira-lazy-load\" style=\"padding-left: 5px; padding-bottom: 10px; padding-right: 5px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-right\"><\/div><a class=\"envira-gallery-8446 envira-gallery-link\" href=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j3.jpg\" title=\"bambola-del-sesso-gainoid-gEh75j3\" data-caption=\"\" data-envira-item-id=\"8456\" data-envira-retina=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j3.jpg\" data-thumb=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j3-75x50_c.jpg\" data-title=\"gainoid-sex-doll-gEh75j3\" data-envirabox='8446' itemprop=\"contentUrl\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j3.jpg\" alt=\"\" class=\"envira-gallery-image envira-gallery-image-4    envira-lazy\" height=\"480\" id=\"envira-gallery-image-8456\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" tabindex=\"-1\" title=\"bambola-del-sesso-gainoid-gEh75j3\" width=\"640\" data-caption=\"\" data-envira-gallery-id=\"8446\" data-envira-index=\"3\" data-envira-item-id=\"8456\" data-envira-src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j3.jpg\" data-envira-srcset=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j3.jpg 400w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j3.jpg 2x\" data-title=\"gainoid-sex-doll-gEh75j3\" itemprop=\"thumbnailUrl\" data-envirabox=\"8446\" data-automatic-caption=\"\" data-envira-height=\"300\" data-envira-width=\"225\" data-envira- data-><\/a><\/div><\/div><div id=\"envira-gallery-item-8453\" class=\"envira-gallery-item envira-gallery-item-5 envira-lazy-load\" style=\"padding-left: 5px; padding-bottom: 10px; padding-right: 5px;\"  itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><div class=\"envira-gallery-item-inner\"><div class=\"envira-gallery-position-overlay envira-gallery-top-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-top-right\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-left\"><\/div><div class=\"envira-gallery-position-overlay envira-gallery-bottom-right\"><\/div><a class=\"envira-gallery-8446 envira-gallery-link\" href=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j1.jpg\" title=\"bambola-del-sesso-gainoid-gEh75j1\" data-caption=\"\" data-envira-item-id=\"8453\" data-envira-retina=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j1.jpg\" data-thumb=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j1-75x50_c.jpg\" data-title=\"gainoid-sex-doll-gEh75j1\" data-envirabox='8446' itemprop=\"contentUrl\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j1.jpg\" alt=\"\" class=\"envira-gallery-image envira-gallery-image-5    envira-lazy\" height=\"480\" id=\"envira-gallery-image-8453\" srcset=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/\/\/\/\/yH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" tabindex=\"-1\" title=\"bambola-del-sesso-gainoid-gEh75j1\" width=\"640\" data-caption=\"\" data-envira-gallery-id=\"8446\" data-envira-index=\"4\" data-envira-item-id=\"8453\" data-envira-src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j1.jpg\" data-envira-srcset=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j1.jpg 400w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j1.jpg 2x\" data-title=\"gainoid-sex-doll-gEh75j1\" itemprop=\"thumbnailUrl\" data-envirabox=\"8446\" data-automatic-caption=\"\" data-envira-height=\"300\" data-envira-width=\"225\" data-envira- data-><\/a><\/div><\/div><\/div><\/div><noscript><img decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j4.jpg\" alt=\"\" class=\"envira_noscript_images\" title=\"\"><img decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j5.jpg\" alt=\"\" class=\"envira_noscript_images\" title=\"\"><img decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j2.jpg\" alt=\"\" class=\"envira_noscript_images\" title=\"\"><img decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j3.jpg\" alt=\"\" class=\"envira_noscript_images\" title=\"\"><img decoding=\"async\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/10\/gainoid-sex-doll-gEh75j1.jpg\" alt=\"\" class=\"envira_noscript_images\" title=\"\"><\/noscript>\n<h5>Ulteriori informazioni<\/h5>\n\t\t<div data-elementor-type=\"section\" data-elementor-id=\"17\" class=\"elementor elementor-17\" data-elementor-post-type=\"elementor_library\">\n\t\t\t<div class=\"elementor-element elementor-element-cd25f6d e-flex e-con-boxed e-con e-parent\" data-id=\"cd25f6d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b22ae5d elementor-widget elementor-widget-heading\" data-id=\"b22ae5d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Colore della pelle opzionale<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d37dda1 elementor-widget elementor-widget-image\" data-id=\"d37dda1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"300\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-funwest-skin.jpg\" class=\"attachment-full size-full wp-image-20432\" alt=\"\" srcset=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-funwest-skin.jpg 1500w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-funwest-skin-350x70.jpg 350w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-funwest-skin-595x119.jpg 595w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-funwest-skin-150x30.jpg 150w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-funwest-skin-768x154.jpg 768w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-funwest-skin-18x4.jpg 18w, https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-funwest-skin-450x90.jpg 450w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14d812a elementor-widget elementor-widget-heading\" data-id=\"14d812a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Immagini ravvicinate di bambole<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4686dd elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"d4686dd\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-1.jpg\" alt=\"guida-irontech-primo-piano-1\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-2.jpg\" alt=\"guida-irontech-primo-piano-2\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-3.jpg\" alt=\"guida-irontech-primo-piano-3\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-4.jpg\" alt=\"guida-irontech-primo-piano-4\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-5.jpg\" alt=\"guida-irontech-primo-piano-5\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-6.jpg\" alt=\"guida-irontech-primo-piano-6\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-9.jpg\" alt=\"guida-irontech-primo-piano-9\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-10.jpg\" alt=\"guida-irontech-primo-piano-10\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-11.jpg\" alt=\"guida-irontech-primo-piano-11\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-13.jpg\" alt=\"guida-irontech-primo-piano-13\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-14.jpg\" alt=\"guida-irontech-primo-piano-14\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-15.jpg\" alt=\"guida-irontech-primo-piano-15\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 de 13\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2025\/01\/guide-irontech-closeup-16.jpg\" alt=\"guida-irontech-primo-piano-16\" title=\"\"><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1609eb5 elementor-widget elementor-widget-heading\" data-id=\"1609eb5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Diverse altezze del corpo in silicone<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54cff36 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"54cff36\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 8\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-zelex-body-zg151a.jpg\" alt=\"guida-zelex-corpo-zg151a\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 8\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-zelex-body-zg155c.jpg\" alt=\"guida-zelex-corpo-zg155c\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 8\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-zelex-body-zg165f.jpg\" alt=\"guida-zelex-corpo-zg165f\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 8\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-zelex-body-zgx165f.jpg\" alt=\"guida-zelex-corpo-zgx165f\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 8\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-zelex-body-zg167e.jpg\" alt=\"guida-zelex-corpo-zg167e\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 8\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-zelex-body-zg170c.jpg\" alt=\"guida-zelex-corpo-zg170c\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 8\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-zelex-body-zg172f.jpg\" alt=\"guida-zelex-corpo-zg172f\" title=\"\"><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 8\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/bomidoll.com\/wp-content\/uploads\/2024\/09\/guide-zelex-body-zg175e.jpg\" alt=\"guida-zelex-corpo-zg175e\" title=\"\"><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5adf981 elementor-widget elementor-widget-text-editor\" data-id=\"5adf981\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>descrizione<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<div data-elementor-type=\"section\" data-elementor-id=\"14\" class=\"elementor elementor-14\" data-elementor-post-type=\"elementor_library\">\n<div class=\"elementor-element elementor-element-e84d306 e-flex e-con-boxed e-con e-parent\" data-id=\"e84d306\" data-element_type=\"container\">\n<div class=\"e-con-inner\">\n<div class=\"elementor-element elementor-element-49bce63 elementor-widget elementor-widget-text-editor\" data-id=\"49bce63\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\n<p>Non esitate a contattarci per maggiori dettagli su questa bambola.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>","protected":false},"featured_media":8453,"template":"","meta":[],"product_cat":[56,52,63,45,70,60,62],"product_tag":[],"class_list":{"0":"post-14994","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-160cm-169cm","7":"product_cat-52","8":"product_cat-asian-sex-doll","9":"product_cat-girl-sex-doll","10":"product_cat-hybrid-sex-doll","11":"product_cat-skinny-sex-doll","12":"product_cat-small-breast-sex-doll","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-simple","19":"add-to-wishlist-after_add_to_cart"},"_links":{"self":[{"href":"https:\/\/bomidoll.com\/it\/wp-json\/wp\/v2\/product\/14994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bomidoll.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bomidoll.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":3,"href":"https:\/\/bomidoll.com\/it\/wp-json\/wp\/v2\/product\/14994\/revisions"}],"predecessor-version":[{"id":22086,"href":"https:\/\/bomidoll.com\/it\/wp-json\/wp\/v2\/product\/14994\/revisions\/22086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bomidoll.com\/it\/wp-json\/wp\/v2\/media\/8453"}],"wp:attachment":[{"href":"https:\/\/bomidoll.com\/it\/wp-json\/wp\/v2\/media?parent=14994"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bomidoll.com\/it\/wp-json\/wp\/v2\/product_cat?post=14994"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bomidoll.com\/it\/wp-json\/wp\/v2\/product_tag?post=14994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}